{"id":13864,"date":"2025-09-15T16:18:30","date_gmt":"2025-09-15T14:18:30","guid":{"rendered":"https:\/\/www.fdss.be\/?p=13864"},"modified":"2025-09-15T16:27:02","modified_gmt":"2025-09-15T14:27:02","slug":"au-coeur-des-services-sociaux-la-maison-des-parents-solos","status":"publish","type":"post","link":"https:\/\/www.fdss.be\/fr\/au-coeur-des-services-sociaux-la-maison-des-parents-solos\/","title":{"rendered":"Au c\u0153ur des services sociaux : La maison des parents solos"},"content":{"rendered":"<div class=\"html-div xdj266r x14z9mp xat24cr x1lziwak xexx8yu xyri2b x18d9i69 x1c1uobl\" dir=\"auto\">\n<div class=\"html-div xdj266r x14z9mp xat24cr x1lziwak xexx8yu xyri2b x18d9i69 x1c1uobl\" data-ad-rendering-role=\"story_message\">\n<div id=\"_R_5anaql6ld5bb6in5klilipamH2_\" class=\"x1l90r2v x1iorvi4 x1g0dm76 xpdmqnj\" data-ad-comet-preview=\"message\" data-ad-preview=\"message\">\n<div class=\"x78zum5 xdt5ytf xz62fqu x16ldp7u\">\n<div class=\"xu06os2 x1ok221b\">\n<div class=\"html-div xdj266r x14z9mp xat24cr x1lziwak xexx8yu xyri2b x18d9i69 x1c1uobl\">\n<div class=\"xdj266r x14z9mp xat24cr x1lziwak x1vvkbs x126k92a\">\n<p dir=\"auto\"><strong>Tous les mois on vous fait d\u00e9couvrir, en vid\u00e9o, l\u2019un des services membres de la F\u00e9d\u00e9ration des Services Sociaux.<\/strong><\/p>\n<\/div>\n<p dir=\"auto\">C\u2019est l\u2019occasion de visibiliser et valoriser toutes ces travailleuses et travailleurs qui se battent contre les in\u00e9galit\u00e9s ! Ils et elles am\u00e9liorent en profondeur la vie des gens et \u0153uvrent au quotidien pour construire une soci\u00e9t\u00e9 plus solidaire\u00a0On ne les montre pas assez mais quel courage il faut, dans le contexte actuel, pour s\u2019engager dans ce sens avec des moyens qui sont de plus en plus rabot\u00e9s&#8230; La FdSS est fi\u00e8re de repr\u00e9senter ces services essentiels et de faire entendre leurs revendications !<\/p>\n<div class=\"x14z9mp xat24cr x1lziwak x1vvkbs xtlvy1s x126k92a\">\n<p dir=\"auto\">Nous d\u00e9marrons avec<strong> la <span class=\"html-span xdj266r x14z9mp xat24cr x1lziwak xexx8yu xyri2b x18d9i69 x1c1uobl x1hl2dhg x16tdsg8 x1vvkbs\"><span class=\"xt0psk2\"><span class=\"xjp7ctv\">Maison des parents solos &#8211; Eenoudergezinnen &lsquo;thuis<\/span><\/span><\/span> <\/strong>, qui offre une bulle d&rsquo;air aux familles monoparentales ainsi qu&rsquo;un accompagnement psycho-social et communautaire.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<p><iframe loading=\"lazy\" title=\"[Au c\u0153ur des services sociaux - \u00c9pisode 1] La maison des parents solos\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/LcgX3C2z070?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tous les mois on vous fait d\u00e9couvrir, en vid\u00e9o, l\u2019un des services membres de la F\u00e9d\u00e9ration des Services Sociaux. C\u2019est l\u2019occasion de visibiliser et valoriser toutes ces travailleuses et travailleurs qui se battent contre les in\u00e9galit\u00e9s ! Ils et elles am\u00e9liorent en profondeur la vie des gens et \u0153uvrent au quotidien pour construire une soci\u00e9t\u00e9 [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":13865,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[46],"tags":[],"class_list":["post-13864","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-membres"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.fdss.be\/fr\/wp-json\/wp\/v2\/posts\/13864","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fdss.be\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fdss.be\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fdss.be\/fr\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fdss.be\/fr\/wp-json\/wp\/v2\/comments?post=13864"}],"version-history":[{"count":6,"href":"https:\/\/www.fdss.be\/fr\/wp-json\/wp\/v2\/posts\/13864\/revisions"}],"predecessor-version":[{"id":13874,"href":"https:\/\/www.fdss.be\/fr\/wp-json\/wp\/v2\/posts\/13864\/revisions\/13874"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fdss.be\/fr\/wp-json\/wp\/v2\/media\/13865"}],"wp:attachment":[{"href":"https:\/\/www.fdss.be\/fr\/wp-json\/wp\/v2\/media?parent=13864"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fdss.be\/fr\/wp-json\/wp\/v2\/categories?post=13864"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fdss.be\/fr\/wp-json\/wp\/v2\/tags?post=13864"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}