{"id":188,"date":"2019-02-06T09:48:31","date_gmt":"2019-02-06T08:48:31","guid":{"rendered":"http:\/\/ry0xytcrk.preview.infomaniak.website\/?page_id=188"},"modified":"2025-10-21T16:52:24","modified_gmt":"2025-10-21T14:52:24","slug":"recherches","status":"publish","type":"page","link":"https:\/\/www.fdss.be\/fr\/crac\/recherches\/","title":{"rendered":"Recherches"},"content":{"rendered":"<div class=\"su-animate\" style=\"opacity:0;-webkit-animation-duration:1s;-webkit-animation-delay:0s;animation-duration:1s;animation-delay:0s;\" data-animation=\"bounceInUp\" data-duration=\"1\" data-delay=\"0\">\n<h4>Les activit\u00e9s de recherche se situent dans le champ de la sociologie de l\u2019action sociale. Elles portent sur les enjeux li\u00e9s aux politiques sociales, \u00e0 l\u2019intervention sociale et aux conditions de vie des personnes pr\u00e9caris\u00e9es.<\/h4>\n<p>Retrouvez toutes les publications en lien avec les recherches ci-dessous <a href=\"https:\/\/www.fdss.be\/type-de-publication\/recherchaction\/#*\">sur cette page.<\/a><\/p>\n<\/div>\n<div class=\"su-animate\" style=\"opacity:0;-webkit-animation-duration:1s;-webkit-animation-delay:0s;animation-duration:1s;animation-delay:0s;\" data-animation=\"bounceInUp\" data-duration=\"1\" data-delay=\"0\">\n<h1><span style=\"color: #de6868;\">Travail social<\/span><\/h1>\n<\/div>\n<div class=\"su-animate\" style=\"opacity:0;-webkit-animation-duration:1s;-webkit-animation-delay:0s;animation-duration:1s;animation-delay:0s;\" data-animation=\"slideInRight\" data-duration=\"1\" data-delay=\"0\">\n<div class=\"title_code\">Am\u00e9liorer la coh\u00e9rence de l'accompagnement des parents avec d\u00e9ficience intellectuelle en FWB (2022-2024)<\/div>\n        <div class=\"content_code\">\n<p>\u00ab Cette recherche, men\u00e9e en collaboration avec l\u2019UMons, l\u2019UCLouvain, l\u2019Araph et l\u2019ULi\u00e8ge et commandit\u00e9e par l\u2019ONE, porte sur les accompagnements des parents porteurs d\u2019une d\u00e9ficience mentale et intellectuelle, en particulier les m\u00e8res. La multiplicit\u00e9 des intervenant-es et des services gravitant autour de ce public sp\u00e9cifique (sociaux, relevant des soins de sant\u00e9, judiciaires, s\u00e9curitaires, etc.), les r\u00f4les et missions endoss\u00e9s par les diff\u00e9rents acteurs (notamment dans leur dimension contraignante ou pas), l\u2019int\u00e9r\u00eat sup\u00e9rieur de l\u2019enfant, les cadres de convention et de collaboration, etc. constituent des n\u0153uds potentiels qui entravent la mise en place d\u2019accompagnements coh\u00e9rents fond\u00e9s sur la confiance et la collaboration entre le public et les professionnel-les.<\/p>\n<p>Une m\u00e9thode d\u2019analyse en groupe (MAG) organis\u00e9e et anim\u00e9e par les chercheuses de la FdSS en automne 2022 et rassemblant des professionnel\u00b7les de terrain a mis \u00e0 jour ces diff\u00e9rentes tensions et a permis la co-construction d\u2019une analyse du travail de proximit\u00e9 aupr\u00e8s de ce public et l\u2019\u00e9nonciation de recommandations pour l\u2019action publique.<\/p>\n<p>Cette MAG s\u2019est inscrit dans un protocole de recherche plus large, impliquant d\u2019autres m\u00e9thodologies (quantitative et qualitative) et aboutissant \u00e0 un rapport de recherche collectif, pr\u00e9sent\u00e9 \u00e0 des r\u00e9seaux d\u2019acteurs professionnels relevant de diff\u00e9rentes sph\u00e8res et disciplines.\u00a0\u00bb<\/p>\n<ul>\n<li><a href=\"https:\/\/www.fdss.be\/wp-content\/uploads\/accompagnement-parents-avec-DMI-rapport.pdf\" target=\"_blank\" rel=\"noopener\">Rapport de recherche: Am\u00e9liorer la coh\u00e9rence de l&rsquo;accompagnement des parents avec d\u00e9ficience intellectuelle<\/a><\/li>\n<li class=\"element-header \"><a href=\"https:\/\/www.one.be\/professionnel\/recherches\/recherches\/2022-2024\/\" target=\"_blank\" rel=\"noopener\">Site ONE Recherches : 2022-2024<\/a><\/li>\n<\/ul>\n<\/div>\n<\/div>\n<div class=\"su-animate\" style=\"opacity:0;-webkit-animation-duration:1s;-webkit-animation-delay:0s;animation-duration:1s;animation-delay:0s;\" data-animation=\"slideInRight\" data-duration=\"1\" data-delay=\"0\">\n<div class=\"title_code\">Documentation\/\u00e9valuation du dispositif num\u00e9ro vert \u00ab Allo ? Aide sociale \u00bb (2020 \u2013 continu)<\/div>\n        <div class=\"content_code\">\n<p>Depuis sa mise en place fin mars 2020 en r\u00e9ponse aux fermetures impos\u00e9es par le contexte sanitaire, le num\u00e9ro vert bruxellois a fait l\u2019objet d\u2019un travail d\u2019\u00e9valuation men\u00e9 par la cellule Recherch\u2019action de la F\u00e9d\u00e9ration des Services Sociaux en collaboration avec les services partenaires du num\u00e9ro vert &#8211; \u00e0 savoir des Centres d\u2019Appui aux Personnes (CAP) et des Centres d\u2019Action Sociale Globale (CASG) de la R\u00e9gion bruxelloise<a href=\"#_edn1\" name=\"_ednref1\"><sup>[i]<\/sup><\/a>.<\/p>\n<p>L\u2019ensemble des constats sur l\u2019aggravation des situations de pr\u00e9carit\u00e9 en r\u00e9gion Bruxelloise am\u00e8ne \u00e0 se demander en quoi et comment le num\u00e9ro \u00ab Allo ? Aide sociale \u00bb est une r\u00e9ponse pertinente pour les personnes en difficult\u00e9. Cela revient \u00e0 d\u00e9crire les contours du m\u00e9tier de r\u00e9pondant\u00b7e, \u00e0 identifier les fonctions qu\u2019il remplit ou ne remplit pas, et la mani\u00e8re dont il s\u2019inscrit dans un syst\u00e8me d\u2019aide sociale fortement affect\u00e9 par le contexte de crise.\u00a0 Le travail d\u2019analyse et d\u2019\u00e9valuation men\u00e9 avec les r\u00e9pondant\u00b7es a permis de d\u00e9finir les aspects bas-seuil, inclusif et anonyme du dispositif \u00ab Allo ? Aide sociale \u00bb, de mod\u00e9liser et baliser ses diff\u00e9rentes modalit\u00e9s d\u2019intervention au d\u00e9part de l\u2019\u00e9change t\u00e9l\u00e9phonique, de penser sa place et son r\u00f4le sp\u00e9cifique parmi les autres 0800 actifs sur la r\u00e9gion bruxelloise et plus globalement, au sein du paysage social bruxellois.<\/p>\n<ul>\n<li><a href=\"https:\/\/www.fdss.be\/wp-content\/uploads\/21-38-A5_Cahier_Recherchaction10_07.pdf\" target=\"_blank\" rel=\"noopener\"><span dir=\"ltr\" role=\"presentation\">Les cahiers <\/span><span dir=\"ltr\" role=\"presentation\">de la <\/span><span dir=\"ltr\" role=\"presentation\">recherch&rsquo;action : Allo? Aide Sociale <\/span><\/a><\/li>\n<\/ul>\n<p>Par ailleurs, le num\u00e9ro \u00ab Allo ? Aide sociale \u00bb fait l\u2019objet de bilans p\u00e9riodiques r\u00e9guliers portants sur le nombre et le type d\u2019appels re\u00e7us au num\u00e9ro vert, jouant en cela un r\u00f4le de thermom\u00e8tre des difficult\u00e9s sociales v\u00e9cues par les Bruxellois-es.<\/p>\n<ul>\n<li><a href=\"https:\/\/www.fdss.be\/type-de-publication\/secteurs\/\" target=\"_blank\" rel=\"noopener\">Bilan des appels re\u00e7us<\/a><\/li>\n<\/ul>\n<p><a href=\"#_ednref1\" name=\"_edn1\">[i]<\/a> <em>Le Centre de Service Social Bruxelles Sud-Est, Brabantia \u2013 SS Cureghem, Les Amis d\u2019Accompagner, Espace P\u2026, Solidarit\u00e9 Savoir, le Service Social Juif, le Centre d\u2019Accueil Social Abb\u00e9 Froidure (Les Petits Riens), le Centre Social Protestant, Wolu-services, l\u2019Espace Social T\u00e9l\u00e9-Service, les Services Sociaux des Quartiers 1030, Brabantia \u2013 Caritas International, CAW Brussel.<\/em><\/p>\n<\/div>\n<\/div>\n<div class=\"su-animate\" style=\"opacity:0;-webkit-animation-duration:1s;-webkit-animation-delay:0s;animation-duration:1s;animation-delay:0s;\" data-animation=\"slideInRight\" data-duration=\"1\" data-delay=\"0\">\n<div class=\"title_code\">La pr\u00e9vention du surendettement au travers d\u2019ateliers collectifs (novembre 2020 \u2013 octobre 2021)<\/div>\n        <div class=\"content_code\">\n<p>Cette e\u0301tude nous a e\u0301te\u0301 confie\u0301e par le Centre d\u2019Appui \u2013 Me\u0301diation de Dettes (CAMD) qui organise depuis 2005 des ateliers de pre\u0301vention du surendettement. L\u2019objectif de l\u2019e\u0301tude e\u0301tait de prendre du recul sur cette pratique, de mettre en perspective les questionnements qui la traversent et de rendre visible ce que les participant\u2219e\u2219s disent en retirer.<\/p>\n<p>Les analyses propose\u0301es s\u2019appuient sur un dispositif de recherche de type \u00ab compre\u0301hensif \u00bb. Cette de\u0301marche s\u2019inte\u0301resse au sens que les individus ou organisations donnent a\u0300 leurs pratiques. Les donne\u0301es ont e\u0301te\u0301 produites au travers de l\u2019observation de huit se\u0301ances d\u2019ateliers mene\u0301es dans quatre organisations diffe\u0301rentes, suivies syste\u0301matiquement d\u2019un entretien de de\u0301briefing avec les animatrices\u00a0; de quatre demi-journe\u0301es d\u2019analyses collectives avec l\u2019e\u0301quipe du CAMD ; et enfin, de douze entretiens approfondis mene\u0301s aupre\u0300s de participant\u2219e\u2219s aux ateliers et de professionnel\u2219le\u2219s des organismes commanditaires.<\/p>\n<ul>\n<li><a href=\"https:\/\/www.fdss.be\/wp-content\/uploads\/22-57-A5_Cahier_Recherchaction13_03.pdf\" target=\"_blank\" rel=\"noopener\"><span dir=\"ltr\" role=\"presentation\">Les cahiers <\/span><span dir=\"ltr\" role=\"presentation\">de la <\/span><span dir=\"ltr\" role=\"presentation\">recherch&rsquo;action<\/span>: <span dir=\"ltr\" role=\"presentation\">Pr\u00e9venir le <\/span><span dir=\"ltr\" role=\"presentation\">surendettement <\/span><span dir=\"ltr\" role=\"presentation\">via des ateliers <\/span><span dir=\"ltr\" role=\"presentation\">collectifs ?<\/span><\/a><\/li>\n<\/ul>\n<\/div>\n<\/div>\n<div class=\"su-animate\" style=\"opacity:0;-webkit-animation-duration:1s;-webkit-animation-delay:0s;animation-duration:1s;animation-delay:0s;\" data-animation=\"slideInRight\" data-duration=\"1\" data-delay=\"0\">\n<div class=\"title_code\">Acc\u00e8s aux droits et travail social aupr\u00e8s des personnes qui ont une activit\u00e9 prostitutionnelle (2019-2021)<\/div>\n        <div class=\"content_code\">\n<h2><strong>Quels sont les n\u0153uds et tensions dans l\u2019accompagnement vers l\u2019acc\u00e8s aux droits des personnes qui ont une activit\u00e9 prostitutionnelle\u00a0?<\/strong><\/h2>\n<p>Projet de recherche-action d\u00e9but\u00e9 en mars 2019, financ\u00e9 par l\u2019\u00abAssociation des Fonds Sociaux F\u00e9d\u00e9raux et Bicommunautaires\u00a0(FE.BI)\u00bb (2019-2021).<\/p>\n<h3>Objet de la recherche : pratiques et n\u0153uds du travail social avec des personnes prostitu\u00e9es<\/h3>\n<p>Les associations d\u2019aide aux personnes prostitu\u00e9es sont confront\u00e9es \u00e0 des difficult\u00e9s nouvelles dans la mise en \u0153uvre de leurs missions sociales et de pr\u00e9vention\u00a0: diversification des contextes et des profils de prostitution, probl\u00e9matiques migratoires, durcissement des politiques de r\u00e9pression de la prostitution de rue, nouveaux canaux de prostitution (2.0), etc. Ces changements viennent interroger les travailleurs sociaux dans leurs pratiques d\u2019accompagnement, notamment dans l\u2019aide \u00e0 l\u2019acc\u00e8s aux droits (en mati\u00e8res de sant\u00e9, de logement, d\u2019\u00e9ducation, etc).<\/p>\n<p>Le projet souhaite approfondir ces questionnements avec les travailleurs sociaux (\u00e0 Bruxelles et en Wallonie) et en dialogue avec les parcours d\u2019acc\u00e8s aux droits des personnes prostitu\u00e9es.<\/p>\n<h3>Objectif : identifier et renforcer les conditions n\u00e9cessaires aux travailleurs sociaux pour fournir un accompagnement de qualit\u00e9<\/h3>\n<ul>\n<li>Rendre visible la fa\u00e7on dont les travailleurs sociaux exercent leur travail et dans quelle mesure les cadres d\u2019action actuels permettent, \u00e0 leurs yeux, la mise en \u0153uvre d\u2019un accompagnement pertinent\u00a0;<\/li>\n<li>Enrichir les travailleurs sociaux et mettre au travail avec eux les n\u0153uds de l\u2019accompagnement sur base des r\u00e9cits de l\u2019exp\u00e9rience des prostitu\u00e9.e.s\u00a0;<\/li>\n<li>Rendre visible la m\u00e9canique de (non-)acc\u00e8s aux droits des personnes prostitu\u00e9es au regard des cadres juridiques et politiques en mati\u00e8re de prostitution\u00a0;<\/li>\n<li>Proposer des lignes d\u2019action concr\u00e8tes pour renforcer les services et les travailleurs de l\u2019aide aux personnes prostitu\u00e9es\u00a0;<\/li>\n<li>Cr\u00e9er, avec les acteurs de terrain, une production artistique \u00ab\u00a0participative\u00a0\u00bb qui, d\u2019une part, soutient l\u2019\u00ab\u00a0\u00e9change de savoirs\u00a0\u00bb et l\u2019appropriation des r\u00e9sultats de recherche par les travailleurs sociaux et, d\u2019autre part, permet de rendre visible \u00e0 un public large, les tensions auxquelles leur travail les confronte.<\/li>\n<\/ul>\n<h3>M\u00e9thode : une recherche participative avec les acteurs de l\u2019aide sociale aux prostitu\u00e9.e.s<\/h3>\n<p>Le projet de recherche a \u00e9t\u00e9 construit sur base d\u2019une rencontre pr\u00e9alable avec les associations membres de la FdSS travaillant aupr\u00e8s de personnes prostitu\u00e9es, afin de pr\u00eater une oreille attentive aux questionnements et difficult\u00e9s des travailleurs sociaux dans leurs pratiques d\u2019accompagnement. Des enjeux multiples ont \u00e9merg\u00e9 et constituent le socle de ce projet de recherche-action.<\/p>\n<p>La recherche a \u00e9t\u00e9 r\u00e9alis\u00e9e selon une approche qualitative (entretiens, observations\/immersions dans le travail social, m\u00e9thode d\u2019analyse en groupe) aupr\u00e8s des travailleurs sociaux et des personnes prostitu\u00e9es. Elle a \u00e9t\u00e9 en outre soumise aux ajustements propres \u00e0 la m\u00e9thode de recherche participative, en mobilisant les associations dans l\u2019analyse et la diffusion des r\u00e9sultats. Cette m\u00e9thode permet l\u2019enrichissement des travailleurs sociaux non seulement par les r\u00e9sultats de l\u2019analyse, mais aussi par leur participation au processus m\u00eame de la recherche et l\u2019\u00e9change\/dialogue entre les savoirs issus de leur exp\u00e9rience de terrain et ceux des chercheurs.<\/p>\n<p><u>Contacts<\/u>\u00a0:<br \/>\n<a href=\"&#x6d;&#97;&#105;l&#x74;&#x6f;&#58;l&#x6f;&#x74;&#116;e&#x2e;&#x64;&#97;m&#x68;&#x75;&#105;s&#x40;&#x66;&#100;s&#x73;&#x2e;&#98;&#101;\">&#x6c;&#111;t&#x74;&#101;&#46;&#x64;&#x61;&#109;&#x68;&#x75;&#105;s&#x40;&#102;d&#x73;&#x73;&#46;&#x62;&#x65;<\/a><\/p>\n<p><a href=\"&#x6d;&#x61;&#105;&#108;to&#x3a;&#x43;&#x68;&#97;rl&#x6f;&#x74;&#x74;&#101;&#46;m&#x61;&#x69;&#x73;&#105;&#110;&#64;&#x66;&#x64;&#x73;&#115;&#46;be\">&#x43;&#x68;&#x61;&#x72;&#x6c;&#x6f;&#x74;&#x74;&#x65;&#x2e;&#x6d;&#x61;&#x69;&#x73;&#x69;&#x6e;&#x40;&#x66;&#x64;&#x73;&#x73;&#x2e;&#98;&#101;<\/a><\/p>\n<h4>Cahiers de la Recherch&rsquo;action issus de cette recherche :<\/h4>\n<p>Damhuis L., Maisin C. (2022).\u00a0<strong>\u00abProstitution et acc\u00e8s aux droits \u2013 La port\u00e9e d\u00e9mocratique du travail social\u00bb<\/strong>,\u00a0<em>Les\u00a0<\/em><em>Cahiers de la recherch\u2019action<\/em>, n\u00b011, Bruxelles : FdSS.<br \/>\n<a class=\"button\" href=\"https:\/\/www.fdss.be\/publication\/prostitution-et-acces-aux-droits-la-portee-democratique-du-travail-social\/\">Consulter<\/a><\/p>\n<p>Damhuis L., Maisin C. (2022).\u00a0<strong>\u00abProstitution et acc\u00e8s aux droits \u2013 La port\u00e9e politique du travail social\u00bb<\/strong>,\u00a0<em>Les\u00a0<\/em><em>Cahiers de la recherch\u2019action<\/em>, n\u00b011, Bruxelles : FdSS.<br \/>\n<a class=\"button\" href=\"https:\/\/www.fdss.be\/publication\/prostitution-et-acces-aux-droits-la-portee-politique-du-travail-social\/\">Consulter<\/a><\/p>\n<h4>Outil : Jeu de carte pour les intervenants de terrain<\/h4>\n<p><a class=\"button\" href=\"https:\/\/www.fdss.be\/wp-content\/uploads\/22-26-CRAC-jeu-selfprint_01HR.pdf\">T\u00e9l\u00e9charger<\/a><\/p>\n<\/div>\n<\/div>\n<div class=\"su-animate\" style=\"opacity:0;-webkit-animation-duration:1s;-webkit-animation-delay:0s;animation-duration:1s;animation-delay:0s;\" data-animation=\"slideInRight\" data-duration=\"1\" data-delay=\"0\">\n<div class=\"title_code\">Les enjeux \u00e9thiques dans le travail social (2016-2018)<\/div>\n        <div class=\"content_code\">\n<h2>Enjeux \u00e9thiques dans le champ de l\u2019intervention sociale : quelles pr\u00e9occupations, analyses et strat\u00e9gies des intervenant(e)s ?<\/h2>\n<p>Recherche internationale collaborative coordonn\u00e9e par l\u2019AIFRIS (Association Internationale pour la Formation, la Recherche et l&rsquo;Intervention Sociale)<\/p>\n<p>La recherche \u00ab\u00a0<em>Enjeux \u00e9thiques dans le champ de l\u2019intervention sociale\u00a0:\u00a0quelles pr\u00e9occupations, analyses et strat\u00e9gies des intervenant(e)s\u00a0?\u00a0\u00bb\u00a0<\/em>est coordonn\u00e9e par l\u2019Association Internationale pour la Formation, la Recherche et l&rsquo;Intervention Sociale (AIFRIS) et se d\u00e9roule dans quatre pays francophones (France, Suisse, Canada et Belgique). Son but est d\u2019identifier les points communs ou au contraire les aspects sp\u00e9cifiques des enjeux, pr\u00e9occupations et probl\u00e8mes \u00e9thiques qui se posent aux intervenants sociaux dans ces diff\u00e9rents contextes nationaux.<\/p>\n<p>Le groupe th\u00e9matique \u00ab\u00a0\u00e9thique\u00a0\u00bb de l\u2019AIFRIS d\u00e9finit les concepts clefs de sa probl\u00e9matique comme ceci\u00a0:<\/p>\n<p>\u00ab\u00a0Par <strong>pr\u00e9occupation \u00e9thique<\/strong>, nous entendons un trouble, un malaise qui peut concerner une\u00a0situation particuli\u00e8re, un mode de fonctionnement habituel (dans une pratique, en lien avec une politique, avec certaines logiques d\u2019intervention, etc.), une d\u00e9cision \u00e0 prendre, et qui met en jeu des valeurs, des questions de sens. Par <strong>probl\u00e8me \u00e9thique<\/strong>, nous entendons un conflit de valeurs entre diff\u00e9rentes mani\u00e8res de mener une intervention sociale, ou, plus largement, une absence de solution \u00e9vidente face \u00e0 un probl\u00e8me engageant des cons\u00e9quences importantes pour soi, pour autrui, et\/ou pour une collectivit\u00e9. Cela peut concerner plus sp\u00e9cifiquement un conflit entre normes organisationnelles \/institutionnelles \/professionnelles \/d\u00e9ontologiques, ou entre normes et valeurs, entre principes et cons\u00e9quences, entre valeurs et int\u00e9r\u00eats en jeu\u00a0; une tension entre g\u00e9n\u00e9ralit\u00e9\u00a0 d\u2019un principe et singularit\u00e9 d\u2019une situation\u00a0; ou encore un manque de rep\u00e8res normatifs pour r\u00e9soudre un probl\u00e8me in\u00e9dit, une absence de r\u00e9ponse institutionnelle par rapport \u00e0 une situation sp\u00e9cifique ou \u00e0 des besoins r\u00e9currents, etc.\u00a0\u00bb (AIFRIS &#8211; Groupe th\u00e9matique Ethique, \u00ab\u00a0L\u2019\u00e9thique en action dans le travail social\u00a0: une recherche collaborative compar\u00e9e\u00a0\u00bb, <em>Pr\u00e9sentation du projet pour les partenaires<\/em>, 20 novembre 2015, p.2 et 3.)<\/p>\n<h3>D\u00e9marche m\u00e9thodologique<\/h3>\n<p>Une approche m\u00e9thodologique commune \u2013 s\u2019inspirant de \u00ab\u00a0la m\u00e9thode d\u2019analyse en groupe\u00a0[MAG]<em><strong>*<\/strong><\/em>\u00bb librement adapt\u00e9e \u00e0 d\u2019\u00e9ventuelles contraintes locales \u2013 est utilis\u00e9e pour <strong>recueillir la parole et l\u2019expertise de travailleurs sociaux<\/strong> au contact de diff\u00e9rentes probl\u00e9matiques et\/ou publics dans chacun de ces pays. Les groupes de professionnels constitu\u00e9s pour contribuer \u00e0 ce travail sont nomm\u00e9s <em>Groupes Locaux Ethiques\u00a0(GLE). <\/em><\/p>\n<p>La MAG, con\u00e7ue par Van Campenhoudt <em>et al. (2005)<\/em> consiste \u00e0 partir de t\u00e9moignages concrets apport\u00e9s par les participants (des \u00ab\u00a0r\u00e9cits\u00a0\u00bb directement issus de leurs r\u00e9alit\u00e9s de travail et r\u00e9v\u00e9lateurs d\u2019une probl\u00e9matique particuli\u00e8re), pour construire une analyse collective \u00e0 travers l\u2019organisation des multiples interpr\u00e9tations qu\u2019ils produisent et ainsi, d\u2019accro\u00eetre la compr\u00e9hension des difficult\u00e9s qu\u2019ils rencontrent dans leur profession et de mieux en saisir les enjeux.<\/p>\n<p><em>*Pour une pr\u00e9sentation d\u00e9taill\u00e9e mais sommes toute plus synth\u00e9tique de cette m\u00e9thode, voir : Van Campenhoudt L.<strong>,<\/strong>\u00a0Franssen\u00a0A. <strong>et <\/strong>Cantelli F., 2009<\/em><\/p>\n<h3>Contribution de la FdSS : \u00ab\u00a0\u00e9thique, travail social et sant\u00e9 mentale\u00a0\u00bb<\/h3>\n<p>Dans un premier temps, la contribution de la FdSS se situe plus particuli\u00e8rement dans l\u2019axe croisant\u00a0travail social, enjeux \u00e9thiques et sant\u00e9 mentale. Une session d\u2019intervision (deux matin\u00e9es) a \u00e9t\u00e9 organis\u00e9e autour de ce th\u00e8me par sa cellule recherch\u2019action dans un double objectif\u00a0:<\/p>\n<ul>\n<li>Dans une perspective de production de connaissances\u00a0: Apporter une <strong>contribution belge<\/strong> \u00e0 cette recherche internationale collaborative<\/li>\n<li>Dans une logique \u00ab\u00a0d\u2019intervision\u00a0\u00bb\u00a0: Proposer aux assistants sociaux participants des <strong>moments de partage d\u2019exp\u00e9riences<\/strong> entre professionnels, de prise de recul et de construction d\u2019analyses collectives, qui leur permettent d\u2019accro\u00eetre leur compr\u00e9hension des difficult\u00e9s rencontr\u00e9es lorsque des probl\u00e8mes de sant\u00e9 mentale s\u2019introduisent dans leur r\u00e9alit\u00e9 de travail.<\/li>\n<\/ul>\n<p>Rapport issu de cette recherche\u00a0: Serr\u00e9 A. et Ayadi A., <strong>\u00ab\u00a0<\/strong><strong>Le travail social au contact de personnes souffrant de probl\u00e9matiques de sant\u00e9 mentale\u00a0\u00bb<\/strong><strong>, <\/strong>Rapport d\u2019intervision, FdSS, septembre 2017. Disponible sur demande.<\/p>\n<\/div>\n<\/div>\n<div class=\"su-animate\" style=\"opacity:0;-webkit-animation-duration:1s;-webkit-animation-delay:0s;animation-duration:1s;animation-delay:0s;\" data-animation=\"slideInRight\" data-duration=\"1\" data-delay=\"0\">\n<div class=\"title_code\">Regards crois\u00e9s usagers et travailleurs sociaux (2013-2015 )<\/div>\n        <div class=\"content_code\">\n<p><a href=\"https:\/\/www.fdss.be\/wp-content\/uploads\/affiche-regards-croises.png\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-842 size-thumbnail\" src=\"https:\/\/www.fdss.be\/wp-content\/uploads\/affiche-regards-croises-106x150.png\" alt=\"\" width=\"106\" height=\"150\" srcset=\"https:\/\/www.fdss.be\/wp-content\/uploads\/affiche-regards-croises-106x150.png 106w, https:\/\/www.fdss.be\/wp-content\/uploads\/affiche-regards-croises-353x500.png 353w, https:\/\/www.fdss.be\/wp-content\/uploads\/affiche-regards-croises.png 595w\" sizes=\"auto, (max-width: 106px) 100vw, 106px\" \/><\/a>La recherche intitul\u00e9e <em>Regards crois\u00e9s : usagers et travailleurs sociaux <\/em>a d\u00e9but\u00e9 en mars 2013. Cette recherche a \u00e9t\u00e9 financ\u00e9e par l\u2019\u00abAssociation des Fonds Sociaux F\u00e9d\u00e9raux et Bicommunautaires\u00a0(FE.BI)\u00bb pour une dur\u00e9e de deux ans. Des financements compl\u00e9mentaires ont, par ailleurs, \u00e9t\u00e9 attribu\u00e9s par les cabinets des Affaires Sociales COCOF, COCOM et wallon.<\/p>\n<p>&nbsp;<\/p>\n<h2><\/h2>\n<h2>Premi\u00e8re partie\u00a0: regards d\u2019usagers<\/h2>\n<p>Les ann\u00e9es 2013 et 2014 ont \u00e9t\u00e9 consacr\u00e9es au recueil de <strong>la parole des usagers<\/strong> afin d\u2019analyser leurs perceptions du travail social en g\u00e9n\u00e9ral et, plus sp\u00e9cifiquement, la fa\u00e7on dont ils vivent l\u2019accueil et les services qui leur sont offerts par les centres membres de la FdSS-FdSSB. 107 entretiens ont \u00e9t\u00e9 r\u00e9alis\u00e9s dans 23 salles d\u2019attente de services sociaux associatifs bruxellois et wallons, mettant au jour la diversit\u00e9 des regards et des exp\u00e9riences v\u00e9cues.<\/p>\n<p><strong>\u00a0<\/strong><strong>L\u2019\u00e9quipe de recherche a pr\u00e9sent\u00e9 une premi\u00e8re s\u00e9rie d\u2019analyses \u00e0 l\u2019occasion de la journ\u00e9e de \u00ab\u00a0Zoom sur l\u2019action sociale\u00a0\u00bb, le 17 f\u00e9vrier 2014.<\/strong> En parall\u00e8le, la cellule recherche, C\u00e9cile Hupin, Guillaume Istace et le CBCS ont inaugur\u00e9 l\u2019espace sc\u00e9nographique \u00ab Paroles d\u2019usagers \u00bb : cette cr\u00e9ation offre une entr\u00e9e plus artistique, traduisant autrement l\u2019intimit\u00e9 des usagers, leur parcours et leur rapport aux services sociaux.<\/p>\n<h2>Deuxi\u00e8me partie: retour vers les professionnels (en cours)<\/h2>\n<p>D\u2019octobre 2014 \u00e0 avril 2015, nous avons organis\u00e9 <strong>des groupes<\/strong> <strong>de travail<\/strong> au sein de chaque centre ayant particip\u00e9 \u00e0 la recherche. Fond\u00e9 sur une d\u00e9marche de co-construction de savoirs entre praticiens et chercheurs, le dispositif d\u2019animation proposait d\u2019<strong>associer les travailleurs sociaux \u00e0 l\u2019analyse des donn\u00e9es r\u00e9colt\u00e9es<\/strong>, sur base de leur point de vue particulier de professionnel, d\u2019une part, et du contexte sp\u00e9cifique de leur centre, d\u2019autre part.<\/p>\n<h2>La diffusion des r\u00e9sultats de la recherche<\/h2>\n<p><strong>Les cinq premiers volumes de la revue \u00ab\u00a0Les Cahiers de la Recherch\u2019action\u00a0\u00bb se consacrent \u00e0 la diffusion des r\u00e9sultats de cette recherche. Privil\u00e9giant un contenu synth\u00e9tique, accessible et mobilisable par diff\u00e9rents types d\u2019acteurs (les professionnels de terrain, les d\u00e9cideurs politiques,\u2026),<\/strong> chaque num\u00e9ro de cette s\u00e9rie approfondit une th\u00e9matique sp\u00e9cifique, \u00e0 la crois\u00e9e des analyses produites par les professionnels et des perceptions des usagers des services.<\/p>\n<p>&nbsp;<\/p>\n<\/div>\n<\/div>\n<div class=\"su-animate\" style=\"opacity:0;-webkit-animation-duration:1s;-webkit-animation-delay:0s;animation-duration:1s;animation-delay:0s;\" data-animation=\"bounceInUp\" data-duration=\"1\" data-delay=\"0\">\n<h1><span style=\"color: #de6868;\">Aide alimentaire<\/span><\/h1>\n<\/div>\n<div class=\"su-animate\" style=\"opacity:0;-webkit-animation-duration:1s;-webkit-animation-delay:0s;animation-duration:1s;animation-delay:0s;\" data-animation=\"slideInRight\" data-duration=\"1\" data-delay=\"0\">\n<div class=\"title_code\">Solidarit\u00e9 en primeur(s) -Solenprim (2016-2019)<\/div>\n        <div class=\"content_code\">\n<h2>\u00ab Solidarit\u00e9 en primeur(s) \u00bb (Solenprim) &#8211; Vers de nouveaux rapprochements entre le secteur de l\u2019aide alimentaire et les syst\u00e8mes d\u2019alimentation durable \u00e0 Bruxelles<\/h2>\n[2016-2018]\n<p class=\"Montitre1\">Financ\u00e9e par Innoviris (l\u2019Institut bruxellois pour la recherche et l\u2019innovation), la recherche-action participative \u00ab\u00a0Solidarit\u00e9 en primeur(s)\u00a0\u00bb, dite <em>Solenprim<\/em>, a d\u00e9but\u00e9 en janvier 2016 pour une dur\u00e9e de trois ans. Elle se fixe l\u2019objectif g\u00e9n\u00e9ral de formaliser de nouveaux rapprochements entre le secteur de l\u2019aide alimentaire et les syst\u00e8mes d\u2019alimentation durable \u00e0 Bruxelles.<\/p>\n<p class=\"Montitre1\">Men\u00e9e suivant un principe de \u00ab co-cr\u00e9ation \u00bb, elle rassemble diff\u00e9rents partenaires : La FdSS (qui coordonne le projet au travers l\u2019implication de sa Cellule recherch\u2019action et de la Concertation Aide alimentaire), le Centre Social Protestant (CSP), La Porte Verte \/ Snijboontje et Snijboontje bis, l\u2019\u00e9picerie sociale du CPAS d\u2019Ixelles, l\u2019\u00e9picerie sociale du CPAS de Berchem-Sainte-Agathe et la plateforme d\u2019achats solidaire Soli-Food.<\/p>\n<h3>Le projet et les objectifs vis\u00e9s<\/h3>\n<p>Le projet Solenprim s\u2019est \u00e9labor\u00e9 autour des objectifs op\u00e9rationnels suivants\u00a0: cr\u00e9er, d\u00e9velopper et \u00e9valuer des dispositifs ou initiatives pilotes permettant aux publics les plus pr\u00e9caires d\u2019acc\u00e9der durablement \u00e0 une alimentation de qualit\u00e9, saine, diversifi\u00e9e, et d\u2019\u00eatre connect\u00e9s \u00e0 des syst\u00e8mes alimentaires alternatifs qui promeuvent de nouvelles formes de solidarit\u00e9s, de coop\u00e9rations et d\u2019\u00e9changes. Il s\u2019agit aussi d\u2019\u00e9laborer des dispositifs qui permettent aux organismes d\u2019aide alimentaire\u00a0 de s\u2019associer davantage \u00e0 cette transition vers des syst\u00e8mes d\u2019alimentation durable.<\/p>\n<h3>Enjeux de connaissance et question de recherche<\/h3>\n<p>La question de recherche principale est\u00a0la suivante :<strong>\u00a0<em>En quoi et comment des dispositifs innovants, associant le secteur de l\u2019aide alimentaire \u00e0 la transition vers un syst\u00e8me alimentaire durable, sont-ils susceptibles d\u2019accro\u00eetre durablement la libert\u00e9 de choix et le champ des usages alimentaires des publics d\u00e9favoris\u00e9s\u00a0?<\/em>\u00a0<\/strong><\/p>\n<p>Cette question principale s\u2019articule en trois types de questions connexes\u00a0:<\/p>\n<ul>\n<li>Des questions op\u00e9rationnelles et strat\u00e9giques directement li\u00e9es aux objectifs g\u00e9n\u00e9raux vis\u00e9s par les partenaires du projet, comme par exemple : Comment connecter durablement les publics pr\u00e9caires \u00e0 ces syst\u00e8mes d\u2019alimentation durable\u00a0?<\/li>\n<li>Des questions de recherche proprement dites, relatives aux r\u00e9alit\u00e9s des b\u00e9n\u00e9ficiaires de l\u2019aide alimentaire,\u00a0aux r\u00e9alit\u00e9s du secteur ou encore au suivi, \u00e0 l\u2019analyse et \u00e0 l\u2019\u00e9valuation des dispositifs innovants qui seront co-cr\u00e9\u00e9s par les partenaires, etc.<\/li>\n<li>Des questions de \u00ab\u00a0m\u00e9ta-recherche\u00a0\u00bb, centr\u00e9es sur le suivi et l\u2019analyse du processus de co-cr\u00e9ation lui-m\u00eame et de ses enjeux.<\/li>\n<\/ul>\n<h3>Calendrier de travail<\/h3>\n<p>Dans l\u2019esprit de la co-cr\u00e9ation, c\u2019est avec les b\u00e9n\u00e9ficiaires de l\u2019aide alimentaire et les travailleurs salari\u00e9s et volontaires du secteur, que\u00a0:<\/p>\n<ul>\n<li>Dans un premier temps (\u00ab\u00a0les racines des difficult\u00e9s\u00a0\u00bb), nous diagnostiquerons le poids des contraintes qui r\u00e9duisent les capacit\u00e9s d\u2019acc\u00e8s \u00e0 une alimentation vari\u00e9e et les possibilit\u00e9s d\u2019usages vari\u00e9s des aliments.<br \/>\n<em>Outils\u00a0: m\u00e9thode Ishikawa, diagnostics locaux, transversaux, crois\u00e9s et \u00ab\u00a0world-smoothies\u00a0\u00bb.<br \/>\n<\/em><\/li>\n<li>Dans un second temps (\u00ab\u00a0des branches aux solutions\u00a0\u00bb), de fa\u00e7on prospective, nous imaginerons diff\u00e9rents dispositifs \u00e0 privil\u00e9gier pour r\u00e9duire le poids de ces contraintes, accro\u00eetre les possibilit\u00e9s de choix alimentaires des personnes d\u00e9favoris\u00e9es et promouvoir des usages diff\u00e9renci\u00e9s des fruits et l\u00e9gumes. Ce travail prospectif sera men\u00e9 avec l\u2019appui d\u2019acteurs p\u00e9riph\u00e9riques susceptibles d\u2019apporter un soutien utile (associations agricoles, Mabru, etc.).<br \/>\n<em>Outils\u00a0: m\u00e9thode d\u2019extrapolation r\u00e9trospective et travail en \u00ab\u00a0charrettes\u00a0\u00bb.<br \/>\n<\/em><\/li>\n<li>Dans un troisi\u00e8me temps (\u00ab\u00a0la r\u00e9colte\u00a0\u00bb), nous impl\u00e9menterons ces dispositifs pilotes au sein des associations partenaires et nous \u00e9valuerons leurs limites et leurs b\u00e9n\u00e9fices respectifs avec les acteurs concern\u00e9s.<br \/>\n<em>Outils\u00a0: m\u00e9thode de suivi et \u00e9valuation participatifs (SEP) et m\u00e9thode d\u2019analyse en groupe (MAG).<br \/>\n<\/em><\/li>\n<li>Transversalement, les aides alimentaires \u00e9tant g\u00e9n\u00e9ralement octroy\u00e9es pour une dur\u00e9e limit\u00e9e, nous nous int\u00e9resserons aussi au caract\u00e8re durable des dynamiques et changements initi\u00e9s \u00e0 travers le suivi de cohortes de b\u00e9n\u00e9ficiaires.<\/li>\n<\/ul>\n<p><strong>Liens\u00a0:<\/strong><\/p>\n<p><a class=\"pdflink\" href=\"https:\/\/www.fdss.be\/wp-content\/uploads\/Innoviris-Pr\u00e9sentation-Solenprim.pdf\">Pr\u00e9sentation PowerPoint du projet Solenprim<\/a><\/p>\n<p><a href=\"https:\/\/solenprim.com\/\" target=\"_blank\" rel=\"noopener\">Site internet Solenprim<\/a><\/p>\n<\/div>\n<\/div>\n<div class=\"su-animate\" style=\"opacity:0;-webkit-animation-duration:1s;-webkit-animation-delay:0s;animation-duration:1s;animation-delay:0s;\" data-animation=\"slideInRight\" data-duration=\"1\" data-delay=\"0\">\n<div class=\"title_code\">L\u2019aide alimentaire aujourd\u2019hui, le droit \u00e0 l\u2019alimentation demain (2014-2015)<\/div>\n        <div class=\"content_code\">\n<p>D\u00e9but\u00e9e en septembre 2014, la recherche \u00ab\u00a0<strong>L\u2019aide alimentaire aujourd\u2019hui, le droit \u00e0 l\u2019alimentation demain\u00a0\u00bb <\/strong>vise l\u2019actualisation des donn\u00e9es d\u2019une pr\u00e9c\u00e9dente \u00e9tude men\u00e9e par la FdSS<sup>[1]<\/sup> sur l\u2019aide alimentaire \u00e0 Bruxelles. Cette derni\u00e8re avait permis de dresser un \u00e9tat des lieux du secteur, essentiellement, au d\u00e9part du point de vue des acteurs de terrain\u00a0; cette nouvelle recherche s&rsquo;est centr\u00e9e davantage sur le regard des b\u00e9n\u00e9ficiaires.<\/p>\n<p>Fruit d\u2019une collaboration entre les cellules\u00a0Aide alimentaire et\u00a0Recherch\u2019action de la FdSS, <strong>cette recherche r\u00e9pond \u00e0 plusieurs objectifs, d\u00e9clin\u00e9s en diff\u00e9rentes phases\u00a0:<\/strong><\/p>\n<h2>Dresser un \u00e9tat des lieux actualis\u00e9 et affin\u00e9 de l\u2019aide alimentaire \u00e0 Bruxelles<\/h2>\n<p>D\u00e9but 2015, la cellule Aide alimentaire a recueilli, aupr\u00e8s des organismes d\u2019aide alimentaire, des informations factuelles (localisation, horaire, nombre de personnes aid\u00e9es,\u2026) qui :<\/p>\n<ul>\n<li>d\u2019une part, constituent une <strong>cartographie interactive<\/strong> destin\u00e9e \u00e0 faciliter les dons adress\u00e9s aux organisations d\u2019aide alimentaire. Sur celle-ci, \u00a0les organismes (publics et associatifs) d\u2019aide alimentaire sont localis\u00e9s: en cliquant sur un organisme, une fiche appara\u00eet, reprenant en synth\u00e8se des informations utiles pour les donataires potentiels (v\u00e9hicule disponible, besoins en denr\u00e9es, jours d\u2019ouverture,\u2026).<\/li>\n<li>d\u2019autre part, fournissent des <strong>donn\u00e9es quantitatives<\/strong> sur les moyens logistiques, les publics et les associations du secteur de l\u2019aide alimentaire \u00e0 Bruxelles\u00a0: ces donn\u00e9es viendront directement alimenter le rapport pr\u00e9sentant les r\u00e9sultats de la recherche en cours.<\/li>\n<\/ul>\n<h2>Accroitre les connaissances disponibles sur les b\u00e9n\u00e9ficiaires des services d\u2019aide alimentaire<\/h2>\n<p>De mars \u00e0 mai 2015, les chercheurs sont all\u00e9s <strong>\u00e0 la rencontre des b\u00e9n\u00e9ficiaires<\/strong> au sein de six organisations d\u2019aide alimentaire (colis, \u00e9piceries sociales, restaurants sociaux). En tout, 32 t\u00e9moignages d\u2019usagers ont \u00e9t\u00e9 recueillis.<\/p>\n<p>L\u2019analyse des entretiens r\u00e9alis\u00e9s a permis de questionner, entre autres, leur parcours, le rapport qu\u2019ils entretiennent au dispositif d\u2019aide alimentaire, aux professionnels, aux autres usagers, ou encore, la mani\u00e8re dont ils appr\u00e9hendent la fin de l\u2019aide alimentaire.<\/p>\n<p><strong>\u00a0<\/strong>Engager une r\u00e9flexion collective entre les acteurs du secteur<\/p>\n<p>A l\u2019occasion d\u2019un premier groupe de travail, organis\u00e9 le 15 janvier 2015, la Cellule Recherch\u2019action de la FdSS s\u2019est r\u00e9unie avec six professionnels du secteur. Cette rencontre a permis de pr\u00e9parer la phase des entretiens qualitatifs de la recherche, <strong>en tenant compte de l\u2019expertise et des pr\u00e9occupations des acteurs de terrain.<\/strong><\/p>\n<p>En juin 2015, les chercheurs ont organis\u00e9 et anim\u00e9 quatre autres s\u00e9ances de groupe de travail avec des travailleurs et b\u00e9n\u00e9voles du secteur de l&rsquo;aide alimentaire et des repr\u00e9sentants de CPAS, afin de poursuivre la production d\u2019analyses collectives.<\/p>\n<p>Les enseignements de cette recherche ont \u00e9t\u00e9 publi\u00e9s sous plusieurs formes\u00a0: un rapport de recherche\u00a0(consultable sur demande); \u00a0Un num\u00e9ro des <a href=\"https:\/\/remote.fdss.be\/owa\/auth\/logon.aspx?replaceCurrent=1&amp;url=https%3a%2f%2fremote.fdss.be%2fowa%2fredir.aspx%3fC%3dqTn98e3HC0uOZC88gOO-Ulm7cNx92NMIQs8swwoR_gn6HFUhTsbCpS027UBnv6tmLCQNeR0bXdQ.%26URL%3dhttp%253a%252f%252fwww.fdss.be%252findex.php%253fpage%253dcahiers-de-la-recherch-action\" target=\"_blank\" rel=\"noopener noreferrer\">Cahiers de la Recherch\u2019action<\/a>\u00a0; un <a href=\"https:\/\/remote.fdss.be\/owa\/redir.aspx?C=qTn98e3HC0uOZC88gOO-Ulm7cNx92NMIQs8swwoR_gn6HFUhTsbCpS027UBnv6tmLCQNeR0bXdQ.&amp;URL=http%3a%2f%2fwww.fdss.be%2fuploads%2fPublications%2fFdSS%2fAide%2520Alimentaire%2fSanteConguguee75_def.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">article<\/a> paru dans le N\u00b0 75 de la revue <em>Sant\u00e9 conjugu\u00e9e.<\/em><\/p>\n<hr \/>\n<p><br clear=\"all\" \/>[1] La recherche-action sur les r\u00e9alit\u00e9s de l&rsquo;aide alimentaire \u00e0 Bruxelles, men\u00e9e par la FdSS-FdSSB entre mars 2007 et f\u00e9vrier 2009, a fait l&rsquo;objet d&rsquo;une publication en f\u00e9vrier 2010\u00a0: HUBERT, H.-O., NIEUWENHUYS, C., 2010, <em>L\u2019aide alimentaire, au c\u0153ur des in\u00e9galit\u00e9s Logiques sociales, <\/em>L\u2019Harmattan, 180 p.<\/p>\n<\/div>\n<\/div>\n<div class=\"su-animate\" style=\"opacity:0;-webkit-animation-duration:1s;-webkit-animation-delay:0s;animation-duration:1s;animation-delay:0s;\" data-animation=\"slideInRight\" data-duration=\"1\" data-delay=\"0\">\n<div class=\"title_code\">Possibilit\u00e9s int\u00e9grantes et activantes de l\u2019aide alimentaire (2012) <\/div>\n        <div class=\"content_code\">\n<h2>Recherche-action concernant les possibilit\u00e9s int\u00e9grantes et activantes de l\u2019aide alimentaire en y associant ses b\u00e9n\u00e9ficiaires d\u2019une mani\u00e8re active<\/h2>\n<p>Ce rapport est le r\u00e9sultat d\u2019une \u00e9tude visant \u00e0 mettre en lumi\u00e8re les possibilit\u00e9s d\u2019int\u00e9gration et d\u2019activation de l\u2019aide alimentaire par l\u2019implication active des usagers.<br \/>\nEn effet, l\u2019aide alimentaire est toujours n\u00e9cessaire en Belgique dans la lutte contre la pr\u00e9carit\u00e9.<\/p>\n<p>Cette \u00e9tude offre une connaissance d\u2019un secteur jusque-l\u00e0 assez m\u00e9connu du grand public et des m\u00e9dias. Elle tente d\u2019identifier les limites et les effets positifs d\u2019une participation des b\u00e9n\u00e9ficiaires de l\u2019aide alimentaire. Les trois objectifs principaux de cette enqu\u00eate sont :<\/p>\n<ul>\n<li>D\u2019offrir un aper\u00e7u du secteur de l\u2019aide alimentaire et de son fonctionnement participatif;<\/li>\n<li>De pr\u00e9senter une s\u00e9rie de pratiques participatives innovantes dans les trois R\u00e9gions du pays;<\/li>\n<li>De proposer une analyse des obstacles, conditions et effets d\u2019une aide alimentaire ax\u00e9e sur l\u2019\u00e9mancipation et de la capacitation.<\/li>\n<\/ul>\n<p><a href=\"https:\/\/www.fdss.be\/type-de-publication\/recherchaction\/\">Cette \u00e9tude a donn\u00e9 lieu \u00e0 une publication en mai 2012.<\/a><\/p>\n<p>&nbsp;<\/p>\n<\/div>\n<\/div>\n<div class=\"su-animate\" style=\"opacity:0;-webkit-animation-duration:1s;-webkit-animation-delay:0s;animation-duration:1s;animation-delay:0s;\" data-animation=\"slideInRight\" data-duration=\"1\" data-delay=\"0\">\n<div class=\"title_code\">Participation des usagers dans le secteur de l\u2019aide alimentaire (2010-2012)<\/div>\n        <div class=\"content_code\">\n<p>Les initiatives qui encouragent une participation des b\u00e9n\u00e9ficiaires de l\u2019aide alimentaire sont minoritaires (participation au niveau manutention, distribution, ateliers ou activit\u00e9s collectives, formations\u2026). Pourtant, la participation des usagers est sans nul doute une perspective \u00e0 explorer si l\u2019on veut que l\u2019aide alimentaire contribue davantage \u00e0 l\u2019\u00e9mancipation des usagers, d\u2019une part, et conforte la promotion du droit \u00e0 une alimentation ad\u00e9quate et durable, d\u2019autre part. Cependant, elle n\u2019en reste pas moins difficile \u00e0 concr\u00e9tiser. Cette \u00e9tude aborde cette question au travers de projets-pilotes de participation dans des associations d\u2019aide alimentaire.<\/p>\n<p><a href=\"https:\/\/www.fdss.be\/type-de-publication\/recherchaction\/\">Cette \u00e9tude a donn\u00e9 lieu \u00e0 une publication en janvier 2012.<\/a><\/p>\n<p>&nbsp;<\/p>\n<\/div>\n<\/div>\n<div class=\"su-animate\" style=\"opacity:0;-webkit-animation-duration:1s;-webkit-animation-delay:0s;animation-duration:1s;animation-delay:0s;\" data-animation=\"slideInRight\" data-duration=\"1\" data-delay=\"0\">\n<div class=\"title_code\">Etude exploratoire et structuration d\u2019un R\u00e9seau d\u2019Epiceries Sociales (REpiS) (2010) <\/div>\n        <div class=\"content_code\">\n<p>Globalement, le secteur de l\u2019aide alimentaire est actuellement tr\u00e8s \u00e9clat\u00e9. Les \u00e9piceries sociales sont des projets compliqu\u00e9s \u00e0 p\u00e9renniser, pour des raisons diverses : difficult\u00e9s d\u2019approvisionnement, de gestion de stocks, de viabilit\u00e9 financi\u00e8re, de personnel\u2026 Face \u00e0 ce constat, l\u2019objectif de cette \u00e9tude \u00e9tait de chercher \u00e0 rassembler les \u00e9piceries sociales pour :<\/p>\n<ul>\n<li>favoriser l\u2019\u00e9change des informations et des bonnes pratiques<\/li>\n<li>am\u00e9liorer la logistique et le financement<\/li>\n<li>soutenir la cr\u00e9ation de nouveaux projets d\u2019\u00e9piceries sociales ou de projets d\u2019\u00e9conomie sociale au sein d\u2019\u00e9piceries sociales existantes.<\/li>\n<\/ul>\n<p><a href=\"https:\/\/www.fdss.be\/type-de-publication\/recherchaction\/\">Cette \u00e9tude a donn\u00e9 lieu \u00e0 une publication en novembre 2010.<\/a><\/p>\n<p>&nbsp;<\/p>\n<\/div>\n<\/div>\n<div class=\"su-animate\" style=\"opacity:0;-webkit-animation-duration:1s;-webkit-animation-delay:0s;animation-duration:1s;animation-delay:0s;\" data-animation=\"slideInRight\" data-duration=\"1\" data-delay=\"0\">\n<div class=\"title_code\">L\u2019aide alimentaire, au c\u0153ur des in\u00e9galit\u00e9s (2007-2008)<\/div>\n        <div class=\"content_code\">\n<h3>Recherche-action sur les r\u00e9alit\u00e9s de l\u2019aide alimentaire \u00e0 Bruxelles<\/h3>\n<p>Etat des lieux des centres de distribution de colis, des restaurants sociaux et des \u00e9piceries sociales. Qui sont-ils, comment fonctionnent-ils, dans quel cadre professionnel, avec quels travailleurs, quel travail social, o\u00f9 trouvent-ils les denr\u00e9es, qui sont les b\u00e9n\u00e9ficiaires de ces centres\u2026 autant de questions auxquelles cette \u00e9tude tente de r\u00e9pondre.<\/p>\n<p><a href=\"https:\/\/www.fdss.be\/publication\/\">Cette recherche a donn\u00e9 lieu \u00e0 l&rsquo;\u00e9dition d&rsquo;un livre chez l\u2019Harmattan dont les r\u00e9f\u00e9rences sont disponibles dans la rubrique publications de ce site.<\/a><\/p>\n<\/div>\n<\/div>\n<div class=\"su-animate\" style=\"opacity:0;-webkit-animation-duration:1s;-webkit-animation-delay:0s;animation-duration:1s;animation-delay:0s;\" data-animation=\"bounceInUp\" data-duration=\"1\" data-delay=\"0\">\n<h1><span style=\"color: #de6868;\">Energie<\/span><\/h1>\n<\/div>\n<div class=\"su-animate\" style=\"opacity:0;-webkit-animation-duration:1s;-webkit-animation-delay:0s;animation-duration:1s;animation-delay:0s;\" data-animation=\"slideInRight\" data-duration=\"1\" data-delay=\"0\">\n<div class=\"title_code\">Acc\u00e8s \u00e0 l\u2019\u00e9nergie aux secteurs de l\u2019aide sociale en R\u00e9gion de Bruxelles-Capitale (2012-2015)<\/div>\n        <div class=\"content_code\">\n<h2>Etude des conditions de possibilit\u00e9 d\u2019extension d\u2019une r\u00e9ponse associative \u00e0 la question de l\u2019acc\u00e8s \u00e0 l\u2019\u00e9nergie aux secteurs de l\u2019aide sociale en R\u00e9gion de Bruxelles-Capitale<\/h2>\n<p>Depuis 2009, \u00ab\u00a0<a href=\"http:\/\/www.socialenergie.be\/\" target=\"_blank\" rel=\"noopener noreferrer\">le\u00a0service \u00e9nergie<\/a> (SE) de la FdSS-FdSSB a \u00e9t\u00e9 test\u00e9, adapt\u00e9 et am\u00e9lior\u00e9 afin de proposer une m\u00e9thodologie et une expertise efficace dans le domaine de la guidance sociale \u00e9nerg\u00e9tique.\u00bb1<\/p>\n<p>Plus de trois ann\u00e9es d\u2019exp\u00e9rience, la satisfaction des m\u00e9nages suivis des Accompagnateurs Energie qui r\u00e9alisent ce suivi et des services sociaux partenaires, confirment l\u2019int\u00e9r\u00eat et la pertinence de l\u2019offre. Aujourd\u2019hui, il convient de penser son avenir et son d\u00e9veloppement.<\/p>\n<p>Actuellement port\u00e9 par 4 ETP de terrain et 1,5 ETP de coordination,\u00a0et en partenariat avec deux uniques secteurs de l\u2019aide sociale (les\u00a0CASG et les CAP), le\u00a0SE ne peut in\u00e9vitablement r\u00e9pondre qu\u2019\u00e0 un nombre limit\u00e9 de demandes. Or, le potentiel dans ces deux secteurs, mais aussi dans d\u2019autres secteurs qui proposent un accompagnement social de premi\u00e8re ligne, est probablement important.<\/p>\n<p>\u00ab\u00a0Bruxelles Environnement souhaite \u00e0 pr\u00e9sent implanter plus largement ce projet afin de r\u00e9pondre aux demandes pouvant \u00e9maner d\u2019autres secteurs sociaux associatifs.\u00a0\u00bb2 Si ces secteurs peuvent proposer une r\u00e9ponse \u00e0 la fois efficace et pertinente \u00e0 des probl\u00e8mes d\u2019acc\u00e8s \u00e0 l\u2019\u00e9nergie, en compl\u00e9mentarit\u00e9 avec les acteurs d\u00e9j\u00e0 pr\u00e9sents, c\u2019est un champ qu\u2019il vaut la peine d\u2019investir.<\/p>\n<p>\u00ab\u00a0Gr\u00e2ce \u00e0 son exp\u00e9rience et \u00e0 sa bonne connaissance institutionnelle, la FdSS, en tant que f\u00e9d\u00e9ration d\u2019associations si\u00e9geant dans plusieurs conseils consultatifs, propose une investigation des besoins sp\u00e9cifiques des secteurs et des meilleures mani\u00e8res, en tenant compte des caract\u00e9ristiques de chaque secteur, de proposer \u00e0 leurs b\u00e9n\u00e9ficiaires un service en mati\u00e8re d\u2019\u00e9nergie. Cette investigation et la construction de pistes, \u00e9tant donn\u00e9 le nombre de secteurs potentiellement concern\u00e9s \u00e0 Bruxelles, est un travail de recherche \u00e0 part enti\u00e8re.\u00a0\u00bb3<\/p>\n<p>A cet effet, un projet de recherche a \u00e9t\u00e9 pr\u00e9sent\u00e9 par la cellule \u00e9nergie de la FdSS \u00e0 l\u2019IBGE et au Cabinet de la Ministre de l\u2019Energie. Depuis le 1<sup>er<\/sup> novembre 2012, et ce pour une dur\u00e9e de trois ann\u00e9es, un chercheur de la FdSS est charg\u00e9 de l\u2019\u00e9tude des conditions de possibilit\u00e9 d\u2019extension du SE.<\/p>\n<p>D\u00e8s la proposition de la FdSS d\u2019\u00e9tendre le service \u00e9nergie \u00e0 d\u2019autres secteurs de l\u2019aide sociale \u00e0 Bruxelles, la volont\u00e9 \u00e9tait claire. Cette extension n\u2019aura de raison d\u2019\u00eatre qu\u2019\u00e0 la condition d\u2019\u00eatre d\u00e9velopp\u00e9e au travers de partenariats et\/ou de collaborations avec les acteurs d\u00e9j\u00e0 pr\u00e9sents en mati\u00e8re d\u2019acc\u00e8s \u00e0 l\u2019\u00e9nergie en R\u00e9gion de Bruxelles-Capitale.<\/p>\n<p>Au travers de la recherche, nous tenterons de comprendre en quoi l\u2019offre du service \u00e9nergie se distingue, s\u2019imbrique et se veut compl\u00e9mentaire des missions en mati\u00e8re d\u2019acc\u00e8s \u00e0 l\u2019\u00e9nergie des CPAS et des (futures) Maisons de l\u2019Energie Huis.<\/p>\n<hr \/>\n<p>1 Institut Bruxellois pour la Gestion de l\u2019Environnement (IBGE)<em>, Appel d\u2019offres g\u00e9n\u00e9ral E12-345, cahier de charges concernant la mise en \u0153uvre d\u2019un service d\u2019accompagnement social en mati\u00e8re d\u2019\u00e9nergie par des travailleurs sociaux en R\u00e9gion de Bruxelles-Capitale, <\/em>27\/04\/2012.<\/p>\n<p><em>2Idem.<\/em><\/p>\n<p>3 F\u00e9d\u00e9ration des services sociaux \u2013 F\u00e9d\u00e9ration des services sociaux bicommunautaires (FdSS-FdSSB), <em>Soumission \u2013 Offre de services en r\u00e9ponse \u00e0 l\u2019appel d\u2019offres Appel d\u2019offres g\u00e9n\u00e9ral E12-345, cahier de charges concernant la mise en \u0153uvre d\u2019un service d\u2019accompagnement social en mati\u00e8re d\u2019\u00e9nergie par des travailleurs sociaux en R\u00e9gion de Bruxelles-Capitale<\/em> (Document interne).<\/p>\n<p>&nbsp;<\/p>\n<\/div>\n<\/div>\n<div class=\"su-animate\" style=\"opacity:0;-webkit-animation-duration:1s;-webkit-animation-delay:0s;animation-duration:1s;animation-delay:0s;\" data-animation=\"bounceInUp\" data-duration=\"1\" data-delay=\"0\">\n<h1><span style=\"color: #de6868;\">Autres<\/span><\/h1>\n<\/div>\n<div class=\"su-animate\" style=\"opacity:0;-webkit-animation-duration:1s;-webkit-animation-delay:0s;animation-duration:1s;animation-delay:0s;\" data-animation=\"slideInRight\" data-duration=\"1\" data-delay=\"0\">\n<div class=\"title_code\">Les assises de l\u2019ambulatoire (2006)<\/div>\n        <div class=\"content_code\">\n<p>D\u2019un long processus de concertation inter-sectorielle est issue une recherche-action sur le th\u00e8me de l\u2019\u00e9valuation qualitative. Proposant une r\u00e9flexion collective et structur\u00e9e \u00e0 une douzaine de secteurs de l\u2019action sociale et de la sant\u00e9, cette d\u00e9marche a mis en \u00e9vidence l\u2019int\u00e9r\u00eat d\u2019une m\u00e9thode de concertation syst\u00e9matique, associant tous les acteurs de l\u2019\u00e9valuation \u00e0 la d\u00e9finition des objectifs poursuivis et des crit\u00e8res retenus pour la mener \u00e0 bien.<\/p>\n<p>Cette \u00e9tude a \u00e9t\u00e9 publi\u00e9e dans la revue BIS (Bruxelles Informations Sociales), n\u00b0156. Le BIS est <a href=\"https:\/\/cbcs.be\/wp-content\/uploads\/2011\/03\/bis_156.pdf\">t\u00e9l\u00e9chargeable ici<\/a>, depuis le site du CBCS, \u00e9diteur.<\/p>\n<\/div>\n<\/div>\n<p>&nbsp;<\/p>\n<div class=\"su-animate\" style=\"opacity:0;-webkit-animation-duration:1s;-webkit-animation-delay:0s;animation-duration:1s;animation-delay:0s;\" data-animation=\"bounceInUp\" data-duration=\"1\" data-delay=\"0\">\n<h1><span style=\"color: #de6868;\">Outreach<\/span><\/h1>\n<\/div>\n<div class=\"su-animate\" style=\"opacity:0;-webkit-animation-duration:1s;-webkit-animation-delay:0s;animation-duration:1s;animation-delay:0s;\" data-animation=\"slideInRight\" data-duration=\"1\" data-delay=\"0\">\n<div class=\"title_code\">Les Bureaux de Recherche et d\u2019Intervention sur les Communs (BRI-Co) (2021 \u2013 en cours)<\/div>\n        <div class=\"content_code\">\n<p><strong>Recherche-intervention financ\u00e9e par la Cocom<\/strong><\/p>\n<p>Depuis d\u00e9cembre 2021, la cellule Recherch\u2019action est engag\u00e9e dans l\u2019accompagnement et l\u2019analyse d\u2019un dispositif d\u2019intervention sociale de quartier, le BRI-Co, qui a pour but d\u2019encourager la mise en place d\u2019actions concr\u00e8tes d\u2019am\u00e9lioration de la qualit\u00e9 de vie de certains territoires bruxellois dits \u00ab rel\u00e9gu\u00e9s \u00bb. Il constitue en ce sens une double opportunit\u00e9 d\u2019agir sur les enjeux de l\u2019acc\u00e8s aux droits et aux services (No\u00ebl, 2016) et de favoriser une redynamisation des d\u00e9mocraties locales.<\/p>\n<p>Ce projet de recherche rel\u00e8ve de la \u00ab\u00a0sociologie de l\u2019intervention\u00a0\u00bb, \u00e0 savoir\u00a0: \u00ab une pratique sp\u00e9cifique de la discipline conduisant le sociologue \u00e0 s\u2019immerger, sur (auto)sollicitation, dans une microsituation, afin d\u2019en proposer une lecture dont les effets (de contenu ou de processus) pourraient participer d\u2019une transformation de ladite situation \u00bb (Herreros, 2001, p. 273). Concr\u00e8tement, en tant qu\u2019intervenant\u2219e\u2219s chercheur\u2219e\u2219s, nous sommes amen\u00e9\u2219e\u2219s \u00e0 remplir plusieurs r\u00f4les qui se nourrissent respectivement\u00a0:<\/p>\n<ul>\n<li><strong>Documentation et production de donn\u00e9es empiriques<\/strong> \u00e0 partir de plusieurs m\u00e9thodologies de recherche (entretiens informels et semi-directifs, observation participante, M\u00e9thode d\u2019Analyse en Groupe, etc.). Ce travail se r\u00e9alise \u00e0 diff\u00e9rents niveaux. Dans le cadre des trois jours de BRI-Co, nous collectons la parole des habitants des quartiers fr\u00e9quent\u00e9s, sur les \u00ab r\u00e9parations \u00bb (changements) \u00e0 entreprendre dans leur milieu de vie ou plus sp\u00e9cifiquement sur une th\u00e9matique d\u00e9finie en amont (la sant\u00e9 physique et mentale, la pr\u00e9carit\u00e9 alimentaire, etc.). Les r\u00e9cits ainsi r\u00e9colt\u00e9s sont mis au service des actions men\u00e9es \u00e0 l\u2019\u00e9chelle des territoires. En les additionnant, ils permettent \u00e9galement d\u2019\u00e9tablir une vue d\u2019ensemble sur les probl\u00e9matiques rencontr\u00e9es dans les quartiers pr\u00e9caris\u00e9s de la r\u00e9gion bruxelloise. Par ailleurs, nous documentons le dispositif \u00ab en train de se faire \u00bb, <em>via <\/em>un syst\u00e8me d\u2019archivage d\u2019observations multiples et d\u2019\u00e9crits (compte-rendu de r\u00e9unions, restitution des BRI-Co, mails, etc.). Nous avons aussi men\u00e9 des entretiens semi-directifs ainsi que des groupes d\u2019analyse collective (sous forme de MAG) avec une s\u00e9rie d\u2019acteurs impliqu\u00e9s dans le projet.<\/li>\n<li><strong>Gestion concr\u00e8te du projet et facilitation de divers espaces de r\u00e9union<\/strong>.<\/li>\n<li><strong>Production de m\u00e9ta-analyse sur le dispositif et ses effets<\/strong>. Partant des donn\u00e9es recueillies, nous analysons les effets concrets du BRI-Co tant dans le sens restreint de l\u2019action concr\u00e8te qu\u2019il permet de mettre en \u0153uvre, que dans le sens large des dynamiques individuelles et collectives qu\u2019il contribue \u00e0 impulser. Ces analyses sont inscrites dans une r\u00e9flexion plus large sur les enjeux et les d\u00e9fis politiques que posent les dispositifs participatifs \u00e0 destination de personnes \u00e9loign\u00e9es de la parole et de l\u2019action publiques, d\u2019une part et, d\u2019autre part, le processus de territorialisation des questions sociales, tout particuli\u00e8rement dans un contexte g\u00e9n\u00e9ralis\u00e9 de d\u00e9fiance envers les autorit\u00e9s publiques.<\/li>\n<\/ul>\n<\/div>\n<\/div>\n<div class=\"su-animate\" style=\"opacity:0;-webkit-animation-duration:1s;-webkit-animation-delay:0s;animation-duration:1s;animation-delay:0s;\" data-animation=\"slideInRight\" data-duration=\"1\" data-delay=\"0\">\n<div class=\"title_code\">Les relais d\u2019action de quartier (RAQ) (2021 \u2013 en cours)<\/div>\n        <div class=\"content_code\">\n<p>En 2021, dix-huit travailleur\u00b7euses sociaux, appel\u00e9\u00b7es Relais d\u2019Action de Quartier (RAQ) ont \u00e9t\u00e9 d\u00e9ploy\u00e9\u00b7es dans des quartiers bruxellois concentrant des difficult\u00e9s socio\u00e9conomiques et des indices de population fragilis\u00e9e avec pour mission de renforcer l\u2019accessibilit\u00e9 aux services sociaux et de soins, et de lutter contre le non-recours aux droits. Financ\u00e9 par la COCOM et coordonn\u00e9 par la FdSSb, ce projet s\u2019inscrit aujourd\u2019hui au sein du Plan Social Sant\u00e9 Int\u00e9gr\u00e9, qui a pour objectif de r\u00e9duire les in\u00e9galit\u00e9s socio-spatiales pr\u00e9sentes sur le territoire bruxellois au travers de la mise en place d\u2019une organisation territoriale de l\u2019offre social-sant\u00e9 au plus proche des besoins locaux.<\/p>\n<p>La posture adopt\u00e9e par les RAQ, appel\u00e9e \u00ab\u00a0aller-vers\u00a0\u00bb ou <em>outreach<\/em>, est un type d\u2019intervention sociale qui a pour principe de <em>sortir des murs <\/em>de l\u2019institution pour aller \u00e0 la rencontre des publics \u00e9loign\u00e9s des politiques sociales et de sant\u00e9 publique, et ainsi s\u2019extirper du rapport qui peut s\u2019exercer de part et d\u2019autre d\u2019un guichet. La sp\u00e9cificit\u00e9 du projet est d\u2019articuler cette posture de l\u2019aller vers avec un travail \u00e0 l\u2019\u00e9chelle du quartier.<\/p>\n<p>Depuis ses d\u00e9buts, le projet RAQ int\u00e8gre un processus de recherche-action nourri par les th\u00e9ories de la sociologie de l\u2019intervention, \u00e0 savoir\u00a0: \u00ab\u00a0une pratique sp\u00e9cifique de la discipline conduisant le\/la sociologue \u00e0 s\u2019immerger, sur (auto)sollicitation, dans une microsituation, afin d\u2019en proposer une lecture dont les effets (de contenu ou de processus) pourraient participer d\u2019une transformation de ladite situation \u00bb (Herreros, 2001, p. 273). Le r\u00f4le des chercheur.euses au sein du projet est de soutenir les travailleur\u00b7euses de terrain dans leurs pratiques et dans la construction de leur m\u00e9tier, et de nourrir la r\u00e9flexion autour des enjeux-cl\u00e9s du projet.<\/p>\n<p><strong>D\u00e9marche m\u00e9thodologique<\/strong><\/p>\n<ul>\n<li><strong>TRAVAIL COLLECTIF:<\/strong> Le d\u00e9ploiement des RAQ sur le terrain a soulev\u00e9 diverses questions quant \u00e0 ce nouveau m\u00e9tier \u00ab en train de se faire \u00bb. Une matin\u00e9e par semaine est d\u00e9di\u00e9e \u00e0 soutenir la r\u00e9flexivit\u00e9 des RAQ sur leurs pratiques et leurs missions mais aussi, sur la vision au fondement du projet. Les chercheur\u00b7euses y animent des <strong>intervisions, <\/strong>des<strong> groupes de travail <\/strong>autour de th\u00e9matiques sp\u00e9cifiques ainsi que des <strong>s\u00e9minaires de r\u00e9flexion<\/strong> \u00e0 partir d\u2019un texte ou autres ressources th\u00e9oriques qui peuvent aider \u00e0 penser certaines questions (aller vers, approche territoriale, non-recours, travail social communautaire, etc.).<\/li>\n<li><strong>SUIVI INDIVIDUELS: <\/strong>Chaque RAQ est suivi par un.e chercheur\u00b7euse afin de <strong>documenter <\/strong>le travail qu\u2019il\u2219elles m\u00e8nent sur leur terrain \u00e0 travers des <strong>observations participantes<\/strong> et des <strong>entretiens individuels.<\/strong> Le\u00b7la chercheur\u00b7euse peut \u00e9galement apporter un soutien m\u00e9thodologique au\u00b7\u00e0 la RAQ dans la mise en \u0153uvre de ses projets.<\/li>\n<li><strong>JOURNAL DE BORD:<\/strong> Chaque RAQ remplit un journal de bord en ligne permettant de documenter les actions et projets men\u00e9s.<\/li>\n<li><strong>FAIRE DES PONTS:<\/strong> L\u2019\u00e9quipe de recherche nourrit \u00e9galement le projet <strong>en faisant des liens avec d\u2019autres initiatives et espaces de r\u00e9flexion<\/strong> (s\u00e9minaires, conf\u00e9rences, colloques, groupes de r\u00e9flexion), port\u00e9s par la FdSS ou d\u2019autres acteurs, en lien avec le travail social, l\u2019approche territoriale, les in\u00e9galit\u00e9s de sant\u00e9, le non-recours aux droits, etc.<\/li>\n<\/ul>\n<p><strong>LIENS<\/strong><\/p>\n<ul>\n<li>Site du projet\u00a0: <a href=\"https:\/\/www.raq.brussels\/fr\/\">https:\/\/www.raq.brussels\/fr\/<\/a><\/li>\n<li>Cahier de la recherche #14 <a href=\"https:\/\/www.fdss.be\/publication\/aller-vers-a-lechelle-dun-territoire-le-projet-des-relais-daction-de-quartier\/\" target=\"_blank\" rel=\"noopener\">\u00ab\u00a0<em>Aller vers \u00e0 l\u2019\u00e9chelle d\u2019un territoire. Le projet des Relais d\u2019Action de Quartier<\/em> \u00bb<\/a><\/li>\n<li><a href=\"https:\/\/raq.brussels\/fr\/allcategories-fr-fr\/document\/document-balise-du-projet-septembre-2022\" target=\"_blank\" rel=\"noopener\">Document balise du projet<\/a><\/li>\n<li><a href=\"https:\/\/raq.brussels\/fr\/allcategories-fr-fr\/document\/document-balise-du-projet-septembre-2022\" target=\"_blank\" rel=\"noopener\">Rapport de recherche 2021<\/a><\/li>\n<\/ul>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp;<\/p>\n","protected":false},"author":4,"featured_media":0,"parent":35,"menu_order":146,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-188","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.fdss.be\/fr\/wp-json\/wp\/v2\/pages\/188","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fdss.be\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.fdss.be\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.fdss.be\/fr\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fdss.be\/fr\/wp-json\/wp\/v2\/comments?post=188"}],"version-history":[{"count":66,"href":"https:\/\/www.fdss.be\/fr\/wp-json\/wp\/v2\/pages\/188\/revisions"}],"predecessor-version":[{"id":14030,"href":"https:\/\/www.fdss.be\/fr\/wp-json\/wp\/v2\/pages\/188\/revisions\/14030"}],"up":[{"embeddable":true,"href":"https:\/\/www.fdss.be\/fr\/wp-json\/wp\/v2\/pages\/35"}],"wp:attachment":[{"href":"https:\/\/www.fdss.be\/fr\/wp-json\/wp\/v2\/media?parent=188"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}